{"id":9743,"date":"2018-02-04T21:22:09","date_gmt":"2018-02-04T19:22:09","guid":{"rendered":"https:\/\/www.eefshp.org\/portfolio-item\/filelliniko-dochio-gia-penes\/"},"modified":"2019-05-03T15:18:54","modified_gmt":"2019-05-03T13:18:54","slug":"filelliniko-dochio-gia-penes","status":"publish","type":"portfolio","link":"https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/","title":{"rendered":"\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc \u03b4\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-15d750bd1b332b34c6e70b077ebbccdf\">\n.flex_column.av-av_one_half-15d750bd1b332b34c6e70b077ebbccdf{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-15d750bd1b332b34c6e70b077ebbccdf av_one_half  avia-builder-el-0  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_image-94b6c312e6cca2245adc0c53b8b2af58\">\n.avia-image-container.av-av_image-94b6c312e6cca2245adc0c53b8b2af58 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-av_image-94b6c312e6cca2245adc0c53b8b2af58 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-av_image-94b6c312e6cca2245adc0c53b8b2af58 av-styling- av-img-linked avia-align-center  avia-builder-el-1  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2-798x1030.jpg\" data-srcset=\"https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2-798x1030.jpg 798w, https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2-600x774.jpg 600w, https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2-233x300.jpg 233w, https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2-768x991.jpg 768w, https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2-546x705.jpg 546w, https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2.jpg 1130w\" data-sizes=\"(max-width: 798px) 100vw, 798px\" class='avia_image '  aria-label='\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc \u03b4\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-7316 avia-img-lazy-loading-not-7316 avia_image ' src=\"https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2.jpg\" alt='' title='\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc \u03b4\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2'  height=\"1458\" width=\"1130\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2.jpg 1130w, https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2-600x774.jpg 600w, https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2-233x300.jpg 233w, https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2-768x991.jpg 768w, https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2-798x1030.jpg 798w, https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2-546x705.jpg 546w\" sizes=\"(max-width: 1130px) 100vw, 1130px\" \/><\/a><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-c8fc129dc35fd1ae2a1e410224d39ea8\">\n.flex_column.av-av_one_half-c8fc129dc35fd1ae2a1e410224d39ea8{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-c8fc129dc35fd1ae2a1e410224d39ea8 av_one_half  avia-builder-el-2  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-0d9f7c73ea299c84ae4acbbd4ba53e5b\">\n#top .av-special-heading.av-av_heading-0d9f7c73ea299c84ae4acbbd4ba53e5b{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-0d9f7c73ea299c84ae4acbbd4ba53e5b .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-0d9f7c73ea299c84ae4acbbd4ba53e5b .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-0d9f7c73ea299c84ae4acbbd4ba53e5b av-special-heading-h3 blockquote modern-quote  avia-builder-el-3  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc \u03b4\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div  class='hr av-av_hr-0ff602b3e980a3377077ff3c1c834df6 hr-default  avia-builder-el-4  el_after_av_heading  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-2bd894dbf2e4bf2c4acf98ce4fbf94aa '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>\u0394\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2 \u03bc\u03b5 \u03bc\u03bf\u03c1\u03c6\u03ae \u0395\u03bb\u03bb\u03b7\u03bd\u03af\u03b4\u03b1\u03c2 (\u0393\u03b1\u03bb\u03bb\u03af\u03b1, \u03b2\u0384 \u03c4\u03ad\u03c4\u03b1\u03c1\u03c4\u03bf 19\u03bf\u03c5 \u03b1\u03b9\u03ce\u03bd\u03b1)<\/p>\n<p>\u03c0\u03bf\u03c1\u03c3\u03b5\u03bb\u03ac\u03bd\u03b7 \u03b5\u03c0\u03b9\u03c7\u03c1\u03c9\u03bc\u03b1\u03c4\u03b9\u03c3\u03bc\u03ad\u03bd\u03b7,<\/p>\n<p>\u03cd\u03c8\u03bf\u03c2: 13,3 cm.<\/p>\n<\/div><\/section><\/p><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0393\u03b1\u03bb\u03bb\u03af\u03b1, \u03b2\u0384 \u03c4\u03ad\u03c4\u03b1\u03c1\u03c4\u03bf 19\u03bf\u03c5 \u03b1\u03b9\u03ce\u03bd\u03b1<\/p>\n","protected":false},"author":5,"featured_media":7316,"template":"","meta":{"inline_featured_image":false,"_exactmetrics_skip_tracking":false,"footnotes":""},"tags":[],"portfolio_entries":[84],"class_list":["post-9743","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-porcelains"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc \u03b4\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2 - \u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc \u03b4\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2 - \u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5\" \/>\n<meta property=\"og:description\" content=\"\u0393\u03b1\u03bb\u03bb\u03af\u03b1, \u03b2\u0384 \u03c4\u03ad\u03c4\u03b1\u03c1\u03c4\u03bf 19\u03bf\u03c5 \u03b1\u03b9\u03ce\u03bd\u03b1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/\" \/>\n<meta property=\"og:site_name\" content=\"\u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-03T13:18:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1130\" \/>\n\t<meta property=\"og:image:height\" content=\"1458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/phmus.org\\\/en\\\/portfolio-item\\\/filelliniko-dochio-gia-penes\\\/\",\"url\":\"https:\\\/\\\/phmus.org\\\/en\\\/portfolio-item\\\/filelliniko-dochio-gia-penes\\\/\",\"name\":\"\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc \u03b4\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2 - \u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phmus.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/phmus.org\\\/en\\\/portfolio-item\\\/filelliniko-dochio-gia-penes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/phmus.org\\\/en\\\/portfolio-item\\\/filelliniko-dochio-gia-penes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/phmus.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2.jpg\",\"datePublished\":\"2018-02-04T19:22:09+00:00\",\"dateModified\":\"2019-05-03T13:18:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/phmus.org\\\/en\\\/portfolio-item\\\/filelliniko-dochio-gia-penes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/phmus.org\\\/en\\\/portfolio-item\\\/filelliniko-dochio-gia-penes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/phmus.org\\\/en\\\/portfolio-item\\\/filelliniko-dochio-gia-penes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/phmus.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2.jpg\",\"contentUrl\":\"https:\\\/\\\/phmus.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2.jpg\",\"width\":1130,\"height\":1458},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/phmus.org\\\/en\\\/portfolio-item\\\/filelliniko-dochio-gia-penes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/phmus.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc \u03b4\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/phmus.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/phmus.org\\\/en\\\/\",\"name\":\"\u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5\",\"description\":\"\u0388\u03c1\u03b3\u03bf \u03c4\u03b7\u03c2 \u0395\u03c4\u03b1\u03b9\u03c1\u03b5\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03c4\u03bf\u03bd \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03c3\u03bc\u03cc \u03ba\u03b1\u03b9 \u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03c3\u03bc\u03cc\",\"publisher\":{\"@id\":\"https:\\\/\\\/phmus.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/phmus.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/phmus.org\\\/en\\\/#organization\",\"name\":\"\u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5\",\"url\":\"https:\\\/\\\/phmus.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/phmus.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/phmus.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_museum_el.png\",\"contentUrl\":\"https:\\\/\\\/phmus.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_museum_el.png\",\"width\":275,\"height\":85,\"caption\":\"\u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5\"},\"image\":{\"@id\":\"https:\\\/\\\/phmus.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc \u03b4\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2 - \u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/","og_locale":"en_US","og_type":"article","og_title":"\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc \u03b4\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2 - \u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5","og_description":"\u0393\u03b1\u03bb\u03bb\u03af\u03b1, \u03b2\u0384 \u03c4\u03ad\u03c4\u03b1\u03c1\u03c4\u03bf 19\u03bf\u03c5 \u03b1\u03b9\u03ce\u03bd\u03b1","og_url":"https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/","og_site_name":"\u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5","article_modified_time":"2019-05-03T13:18:54+00:00","og_image":[{"width":1130,"height":1458,"url":"https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/","url":"https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/","name":"\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc \u03b4\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2 - \u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5","isPartOf":{"@id":"https:\/\/phmus.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/#primaryimage"},"image":{"@id":"https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/#primaryimage"},"thumbnailUrl":"https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2.jpg","datePublished":"2018-02-04T19:22:09+00:00","dateModified":"2019-05-03T13:18:54+00:00","breadcrumb":{"@id":"https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/#primaryimage","url":"https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2.jpg","contentUrl":"https:\/\/phmus.org\/wp-content\/uploads\/2018\/02\/\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc-\u03b4\u03bf\u03c7\u03b5\u03af\u03bf-\u03b3\u03b9\u03b1-\u03c0\u03ad\u03bd\u03b5\u03c2.jpg","width":1130,"height":1458},{"@type":"BreadcrumbList","@id":"https:\/\/phmus.org\/en\/portfolio-item\/filelliniko-dochio-gia-penes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/phmus.org\/en\/"},{"@type":"ListItem","position":2,"name":"\u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03cc \u03b4\u03bf\u03c7\u03b5\u03af\u03bf \u03b3\u03b9\u03b1 \u03c0\u03ad\u03bd\u03b5\u03c2"}]},{"@type":"WebSite","@id":"https:\/\/phmus.org\/en\/#website","url":"https:\/\/phmus.org\/en\/","name":"\u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5","description":"\u0388\u03c1\u03b3\u03bf \u03c4\u03b7\u03c2 \u0395\u03c4\u03b1\u03b9\u03c1\u03b5\u03af\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03c4\u03bf\u03bd \u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03c3\u03bc\u03cc \u03ba\u03b1\u03b9 \u03a6\u03b9\u03bb\u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03c3\u03bc\u03cc","publisher":{"@id":"https:\/\/phmus.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/phmus.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/phmus.org\/en\/#organization","name":"\u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5","url":"https:\/\/phmus.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/phmus.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/phmus.org\/wp-content\/uploads\/2021\/04\/logo_museum_el.png","contentUrl":"https:\/\/phmus.org\/wp-content\/uploads\/2021\/04\/logo_museum_el.png","width":275,"height":85,"caption":"\u039c\u039f\u03a5\u03a3\u0395\u0399\u039f \u03a6\u0399\u039b\u0395\u039b\u039b\u0397\u039d\u0399\u03a3\u039c\u039f\u03a5"},"image":{"@id":"https:\/\/phmus.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/phmus.org\/en\/wp-json\/wp\/v2\/portfolio\/9743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phmus.org\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/phmus.org\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/phmus.org\/en\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":1,"href":"https:\/\/phmus.org\/en\/wp-json\/wp\/v2\/portfolio\/9743\/revisions"}],"predecessor-version":[{"id":9744,"href":"https:\/\/phmus.org\/en\/wp-json\/wp\/v2\/portfolio\/9743\/revisions\/9744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/phmus.org\/en\/wp-json\/wp\/v2\/media\/7316"}],"wp:attachment":[{"href":"https:\/\/phmus.org\/en\/wp-json\/wp\/v2\/media?parent=9743"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phmus.org\/en\/wp-json\/wp\/v2\/tags?post=9743"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/phmus.org\/en\/wp-json\/wp\/v2\/portfolio_entries?post=9743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}